{"id":2319,"date":"2021-04-03T11:01:56","date_gmt":"2021-04-03T09:01:56","guid":{"rendered":"http:\/\/srhgx.be\/wordpress\/?p=2319"},"modified":"2021-04-03T19:01:02","modified_gmt":"2021-04-03T17:01:02","slug":"manuel-pratique-du-jardin-climatique","status":"publish","type":"post","link":"http:\/\/srhgx.be\/wordpress\/manuel-pratique-du-jardin-climatique\/","title":{"rendered":"Manuel pratique du jardin climatique"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><span style=\"color:#0673a2\" class=\"has-inline-color\">Marc Verachtert et Bart Verelst<\/span><br>\u00c9d. Racine &#8211; 11\/02\/2020 (19,99 \u20ac)<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Oasis de fra\u00eecheur pour les \u00e9t\u00e9s torrides<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><a href=\"https:\/\/www.racine.be\/fr\/manuel-pratique-du-jardin-climatique\"><img fetchpriority=\"high\" decoding=\"async\" width=\"316\" height=\"392\" src=\"http:\/\/srhgx.be\/wordpress\/wp-content\/uploads\/2021\/04\/image-2.png\" alt=\"\" class=\"wp-image-2322\" srcset=\"http:\/\/srhgx.be\/wordpress\/wp-content\/uploads\/2021\/04\/image-2.png 316w, http:\/\/srhgx.be\/wordpress\/wp-content\/uploads\/2021\/04\/image-2-242x300.png 242w\" sizes=\"(max-width: 316px) 100vw, 316px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Prot\u00e9gez votre jardin contre le changement du climat<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des interventions simples pour prot\u00e9ger votre jardin contre les conditions climatiques extr\u00eames<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des astuces pour choisir les bonnes plantes et g\u00e9rer l&rsquo;eau de mani\u00e8re optimale, mais aussi pour rendre votre fa\u00e7ade et votre terrasse moins sensibles au climat<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9crit par deux experts du jardinage par excellence<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Face \u00e0 l&rsquo;alternance de vagues de chaleur, de p\u00e9riodes de s\u00e9cheresse et d&rsquo;averses diluviennes, nous devrons adapter nos jardins si nous voulons continuer \u00e0 en profiter. Avec les astuces et les concepts de Marc Verachtert et Bart Verelst, votre jardin sera une oasis de fra\u00eecheur m\u00eame au plus fort de la canicule, tandis que le vent et la pluie ne viendront plus g\u00e2cher votre plaisir. Avec des arbres d&rsquo;ombrage et d&rsquo;autres formes de verdure, un tapis d&rsquo;herbe r\u00e9sistant tout au long de l&rsquo;ann\u00e9e, un positionnement ad\u00e9quat de haies ou d&rsquo;\u00e9crans de jardin, un \u00e9tang ou un autre \u00e9l\u00e9ment aquatique, vous r\u00e9gulez la temp\u00e9rature dans votre jardin et pouvez m\u00eame vous y installer et en profiter lors des journ\u00e9es les plus chaudes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Votre contribution a en m\u00eame temps un impact sur le climat dans votre rue et votre voisinage, car elle rafra\u00eechit aussi votre environnement. Plus nous serons nombreux \u00e0 jardiner de la sorte, meilleur sera le climat dans nos villes !<\/p>\n<div class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend pgfw-icon-display pgfw-icon-display--default\" style=\"--pgfw-icon-justify:center;\"><a href=\"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/posts\/2319?action=genpdf&#038;id=2319\" class=\"pgfw-single-pdf-download-button pgfw-single-pdf-download-button--default pgfw-single-pdf-download-button--icon-only\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"--pgfw-icon-width:25px;--pgfw-icon-height:45px;\" aria-label=\"Download PDF\"><span class=\"pgfw-single-pdf-download-button__media\" aria-hidden=\"true\"><img src=\"http:\/\/srhgx.be\/wordpress\/wp-content\/plugins\/pdf-generator-for-wp\/admin\/src\/images\/PDF_Tray.svg\" alt=\"\" decoding=\"async\"><\/span><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Marc Verachtert et Bart Verelst\u00c9d. Racine &#8211; 11\/02\/2020 (19,99 \u20ac) Oasis de fra\u00eecheur pour les \u00e9t\u00e9s torrides Prot\u00e9gez votre jardin contre le changement du climat Des interventions simples pour prot\u00e9ger&hellip;&nbsp;<a href=\"http:\/\/srhgx.be\/wordpress\/manuel-pratique-du-jardin-climatique\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">Manuel pratique du jardin climatique<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[110,1],"tags":[236,112,145,235],"ppma_author":[447],"class_list":["post-2319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livre","category-srhgx","tag-climat","tag-jardin","tag-livre-de-jardinage","tag-manuel"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:39:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"authors":[{"term_id":447,"user_id":10,"is_guest":0,"slug":"cblancke","display_name":"Christine BLANCKE","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/973b599229553ee0b848ec49ca3de61a676ccbea8c5d03d2f477ac1a73794615?s=96&d=mm&r=g","author_category":"","user_url":"","last_name":"BLANCKE","first_name":"Christine","job_title":"","description":""}],"_links":{"self":[{"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/posts\/2319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/comments?post=2319"}],"version-history":[{"count":5,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/posts\/2319\/revisions"}],"predecessor-version":[{"id":2358,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/posts\/2319\/revisions\/2358"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/media\/783"}],"wp:attachment":[{"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/media?parent=2319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/categories?post=2319"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/tags?post=2319"},{"taxonomy":"author","embeddable":true,"href":"http:\/\/srhgx.be\/wordpress\/wp-json\/wp\/v2\/ppma_author?post=2319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}